{"id":1005,"date":"2024-01-25T15:09:07","date_gmt":"2024-01-25T12:09:07","guid":{"rendered":"https:\/\/blog.tamatemplus.com\/?p=1005"},"modified":"2024-02-28T15:48:14","modified_gmt":"2024-02-28T12:48:14","slug":"%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85","status":"publish","type":"post","link":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/","title":{"rendered":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1005\" class=\"elementor elementor-1005\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05af863 e-flex e-con-boxed e-con e-parent\" data-id=\"05af863\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efc6f39 elementor-widget elementor-widget-text-editor\" data-id=\"efc6f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0641\u064a \u0627\u0644\u0639\u0635\u0631 \u0627\u0644\u0631\u0642\u0645\u064a \u0627\u0644\u062d\u0627\u0644\u064a\u060c \u062a\u0639\u062f \u0627\u0644\u0645\u0631\u0648\u0646\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0623\u0645\u0631\u064b\u0627 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629. \u0648\u0644\u0630\u0644\u0643\u060c \u0623\u062d\u062f\u062b \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u062b\u0648\u0631\u0629 \u0641\u064a \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u062c\u0645\u0648\u0639\u0629 \u0631\u0627\u0626\u0639\u0629 \u0645\u0646 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0645\u062e\u062a\u0644\u0641\u0629. \u064a\u062a\u0637\u0631\u0642 \u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u0634\u0648\u0631 \u0625\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u062a\u0645\u0643\u064a\u0646 \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0647\u0630\u0647 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633.<\/p><p>\u0642\u0648\u0629 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0641\u064a \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639<\/p><p>\u0645\u0639 45 \u062e\u064a\u0627\u0631\u064b\u0627 \u0644\u0644\u062f\u0641\u0639\u060c \u064a\u0642\u0641 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0641\u064a \u0637\u0644\u064a\u0639\u0629 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u062a\u062c\u0627\u0631\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0627\u0644\u0645\u0631\u064a\u062d\u0629. \u064a\u0644\u0628\u064a \u0647\u0630\u0627 \u0627\u0644\u062a\u0646\u0648\u0639 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u062c\u0645\u0647\u0648\u0631 \u0639\u0627\u0644\u0645\u064a\u060c \u0645\u0645\u0627 \u064a\u0636\u0645\u0646 \u0623\u0646\u0647 \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0645\u0643\u0627\u0646 \u0648\u062c\u0648\u062f\u0643 \u0623\u0648 \u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u0641\u0636\u0644\u0629 \u0644\u062f\u064a\u0643\u060c \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0623\u0644\u0639\u0627\u0628\u0643 \u0627\u0644\u0645\u0641\u0636\u0644\u0629 \u062f\u0648\u0646 \u0623\u064a \u0645\u062a\u0627\u0639\u0628.<\/p><p>\u0623\u0646\u0648\u0627\u0639 \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0627\u062d\u0629<\/p><p>\u062a\u0634\u0645\u0644 \u0645\u062c\u0645\u0648\u0639\u0629 \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0639\u0644\u0649 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0645\u0627 \u064a\u0644\u064a:<\/p><p>\u0628\u0637\u0627\u0642\u0627\u062a \u0627\u0644\u0627\u0626\u062a\u0645\u0627\u0646 \u0648\u0627\u0644\u062e\u0635\u0645: \u062a\u0634\u0645\u0644 \u0647\u0630\u0647 \u0627\u0644\u0628\u0637\u0627\u0642\u0627\u062a \u0645\u0642\u062f\u0645\u064a \u0627\u0644\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u064a\u0646 \u0645\u062b\u0644 \u0641\u064a\u0632\u0627 \u0648\u0645\u0627\u0633\u062a\u0631\u0643\u0627\u0631\u062f.<\/p><p>\u0627\u0644\u0645\u062d\u0627\u0641\u0638 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u062a\u0648\u0641\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062d\u062f\u064a\u062b\u0629 \u0648\u0627\u0644\u0622\u0645\u0646\u0629 \u0645\u062b\u0644 PayPal \u0648Skrill \u0623\u0633\u0644\u0648\u0628\u0627\u064b \u0631\u0642\u0645\u064a\u064b\u0627 \u0644\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a.<\/p><p>\u0627\u0644\u062f\u0641\u0639 \u0639\u0628\u0631 \u0627\u0644\u0647\u0627\u062a\u0641 \u0627\u0644\u0645\u062d\u0645\u0648\u0644: \u0644\u062a\u0644\u0628\u064a\u0629 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0646\u0645\u0637 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u0633\u0631\u064a\u0639\u060c \u062a\u0639\u0645\u0644 \u062e\u062f\u0645\u0627\u062a \u0645\u062b\u0644 Apple Pay \u0648Google Pay \u0639\u0644\u0649 \u062a\u0628\u0633\u064a\u0637 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0634\u0631\u0627\u0621.<\/p><p>\u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u062d\u0644\u064a\u0629 \u0648\u0627\u0644\u0625\u0642\u0644\u064a\u0645\u064a\u0629: \u0645\u0646 \u062e\u0644\u0627\u0644 \u0641\u0647\u0645 \u0627\u0644\u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0627\u0644\u0641\u0631\u064a\u062f\u0629 \u0644\u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u0645\u0646\u0627\u0637\u0642\u060c \u064a\u062a\u0636\u0645\u0646 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0637\u0631\u0642 \u062f\u0641\u0639 \u0645\u062d\u0644\u064a\u0629 \u062e\u0627\u0635\u0629 \u0628\u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u0628\u0644\u062f\u0627\u0646.<\/p><p>\u0644\u0645\u0627\u0630\u0627 \u064a\u0639\u062a\u0628\u0631 \u0647\u0630\u0627 \u0627\u0644\u062a\u0646\u0648\u0639 \u0645\u0647\u0645\u0627\u064b\u061f<\/p><p>\u0627\u0644\u0634\u0645\u0648\u0644\u064a\u0629: \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639\u060c \u064a\u0636\u0645\u0646 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0625\u0645\u0643\u0627\u0646\u064a\u0629 \u0648\u0635\u0648\u0644 \u0627\u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0645\u0646 \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0639\u0627\u0644\u0645 \u0625\u0644\u0649 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a\u0647\u0645.<\/p><p>\u0627\u0644\u0631\u0627\u062d\u0629: \u064a\u0645\u0643\u0646 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631 \u0627\u0644\u0623\u0643\u062b\u0631 \u0645\u0644\u0627\u0621\u0645\u0629 \u0644\u0647\u0645\u060c \u0645\u0645\u0627 \u064a\u0624\u062f\u064a \u0625\u0644\u0649 \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0623\u0643\u062b\u0631 \u0633\u0644\u0627\u0633\u0629 \u0648\u0645\u062a\u0639\u0629.<\/p><p>\u0627\u0644\u0623\u0645\u0627\u0646: \u0645\u0646 \u062e\u0644\u0627\u0644 \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0639\u062f\u062f\u0629 \u0630\u0627\u062a \u0627\u0644\u0633\u0645\u0639\u0629 \u0627\u0644\u0637\u064a\u0628\u0629\u060c \u064a\u0645\u0643\u0646 \u0644\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0630\u064a \u064a\u062b\u0642\u0648\u0646 \u0641\u064a\u0647 \u0643\u062b\u064a\u0631\u064b\u0627\u060c \u0645\u0645\u0627 \u064a\u0636\u0645\u0646 \u0631\u0627\u062d\u0629 \u0627\u0644\u0628\u0627\u0644 \u0641\u064a \u0643\u0644 \u0645\u0639\u0627\u0645\u0644\u0629.<\/p><p>\u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0633\u0644\u0633\u0629 \u0644\u0644\u0623\u0644\u0639\u0627\u0628<\/p><p>\u064a\u0624\u062f\u064a \u0625\u062f\u0631\u0627\u062c \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0647\u0630\u0647 \u0625\u0644\u0649 \u0625\u062d\u062f\u0627\u062b \u062a\u062d\u0648\u0644 \u0641\u064a \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633. \u064a\u0645\u0643\u0646 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0627\u0644\u0622\u0646 \u0634\u062d\u0646 \u0627\u0644\u0631\u0635\u064a\u062f \u0644\u0644\u0623\u0644\u0639\u0627\u0628 \u0648\u0634\u0631\u0627\u0621 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u0642\u0627\u0628\u0644 \u0644\u0644\u062a\u0646\u0632\u064a\u0644 \u0648\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0623\u062e\u0631\u0649 \u0627\u0644\u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0628\u0633\u0631\u0639\u0629 \u0648\u0623\u0645\u0627\u0646\u060c \u0645\u0645\u0627 \u064a\u0624\u062f\u064a \u0625\u0644\u0649 \u062c\u0644\u0633\u0627\u062a \u0644\u0639\u0628 \u0637\u0648\u064a\u0644\u0629 \u0645\u0645\u062a\u0639\u0629.<\/p><p>\u064a\u0639\u062f \u062a\u0642\u062f\u064a\u0645 45 \u0637\u0631\u064a\u0642\u0629 \u0644\u0644\u062f\u0641\u0639 \u0639\u0644\u0649 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u062c\u0631\u062f \u0645\u064a\u0632\u0629\u061b \u0625\u0646\u0647 \u0627\u0644\u062a\u0632\u0627\u0645 \u0628\u062a\u0648\u0641\u064a\u0631 \u062a\u062c\u0631\u0628\u0629 \u062a\u0633\u0648\u0642 \u0633\u0644\u0633\u0629 \u0648\u0634\u0627\u0645\u0644\u0629 \u0648\u0622\u0645\u0646\u0629 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0639\u0627\u0644\u0645. \u0648\u0645\u0639 \u0647\u0630\u0627 \u0627\u0644\u062a\u0646\u0648\u0639 \u0641\u064a \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062f\u0641\u0639\u060c \u0641\u0625\u0646 \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u0644\u064a\u0633 \u0645\u062c\u0631\u062f \u0645\u0646\u0635\u0629\u061b \u0625\u0646\u0647 \u0628\u0648\u0627\u0628\u0629 \u0644\u0645\u063a\u0627\u0645\u0631\u0627\u062a \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0627\u0644\u062a\u064a \u0644\u0627 \u0646\u0647\u0627\u064a\u0629 \u0644\u0647\u0627.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0641\u064a \u0627\u0644\u0639\u0635\u0631 \u0627\u0644\u0631\u0642\u0645\u064a \u0627\u0644\u062d\u0627\u0644\u064a\u060c \u062a\u0639\u062f \u0627\u0644\u0645\u0631\u0648\u0646\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0623\u0645\u0631\u064b\u0627 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629. \u0648\u0644\u0630\u0644\u0643\u060c \u0623\u062d\u062f\u062b \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u062b\u0648\u0631\u0629 \u0641\u064a \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u062c\u0645\u0648\u0639\u0629 \u0631\u0627\u0626\u0639\u0629 \u0645\u0646 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0645\u062e\u062a\u0644\u0641\u0629. \u064a\u062a\u0637\u0631\u0642 \u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u0634\u0648\u0631 \u0625\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u062a\u0645\u0643\u064a\u0646 \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0647\u0630\u0647 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633. \u0642\u0648\u0629 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0641\u064a \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0645\u0639 45 \u062e\u064a\u0627\u0631\u064b\u0627 [&hellip;]<\/p>","protected":false},"author":12,"featured_media":786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,39],"tags":[],"class_list":["post-1005","post","type-post","status-publish","format-standard","has-post-thumbnail","category-41","category-39"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.tamatemplus.com\/ar\/\u0625\u0637\u0644\u0627\u0642-\u0627\u0644\u0639\u0646\u0627\u0646-\u0644\u0644\u0623\u0644\u0639\u0627\u0628-45-\u0637\u0631\u064a\u0642\u0629-\u062f\u0641\u0639-\u0639\u0644\u0649-\u0637\u0645\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\" \/>\n<meta property=\"og:description\" content=\"\u0641\u064a \u0627\u0644\u0639\u0635\u0631 \u0627\u0644\u0631\u0642\u0645\u064a \u0627\u0644\u062d\u0627\u0644\u064a\u060c \u062a\u0639\u062f \u0627\u0644\u0645\u0631\u0648\u0646\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0623\u0645\u0631\u064b\u0627 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629. \u0648\u0644\u0630\u0644\u0643\u060c \u0623\u062d\u062f\u062b \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u062b\u0648\u0631\u0629 \u0641\u064a \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u062c\u0645\u0648\u0639\u0629 \u0631\u0627\u0626\u0639\u0629 \u0645\u0646 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0645\u062e\u062a\u0644\u0641\u0629. \u064a\u062a\u0637\u0631\u0642 \u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u0634\u0648\u0631 \u0625\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u062a\u0645\u0643\u064a\u0646 \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0647\u0630\u0647 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633. \u0642\u0648\u0629 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0641\u064a \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0645\u0639 45 \u062e\u064a\u0627\u0631\u064b\u0627 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.tamatemplus.com\/ar\/\u0625\u0637\u0644\u0627\u0642-\u0627\u0644\u0639\u0646\u0627\u0646-\u0644\u0644\u0623\u0644\u0639\u0627\u0628-45-\u0637\u0631\u064a\u0642\u0629-\u062f\u0641\u0639-\u0639\u0644\u0649-\u0637\u0645\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T12:09:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T12:48:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tamatem Plus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tamatem Plus\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/\"},\"author\":{\"name\":\"Tamatem Plus\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/#\\\/schema\\\/person\\\/d65a0484622d86e27361954aabfdbca7\"},\"headline\":\"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\",\"datePublished\":\"2024-01-25T12:09:07+00:00\",\"dateModified\":\"2024-02-28T12:48:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/\"},\"wordCount\":6,\"image\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/45-Payment-Methods.png\",\"articleSection\":[\"\u0627\u062d\u0635\u0627\u0626\u064a\u0627\u062a\",\"\u0627\u062e\u0628\u0627\u0631\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/\",\"url\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/\",\"name\":\"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/45-Payment-Methods.png\",\"datePublished\":\"2024-01-25T12:09:07+00:00\",\"dateModified\":\"2024-02-28T12:48:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/#\\\/schema\\\/person\\\/d65a0484622d86e27361954aabfdbca7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/45-Payment-Methods.png\",\"contentUrl\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/45-Payment-Methods.png\",\"width\":1792,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/\",\"name\":\"\u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/#\\\/schema\\\/person\\\/d65a0484622d86e27361954aabfdbca7\",\"name\":\"Tamatem Plus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/new-tamatem-header-150x150-1.png\",\"url\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/new-tamatem-header-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/blog.tamatemplus.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/new-tamatem-header-150x150-1.png\",\"caption\":\"Tamatem Plus\"},\"url\":\"https:\\\/\\\/blog.tamatemplus.com\\\/ar\\\/author\\\/tamatemplus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.tamatemplus.com\/ar\/\u0625\u0637\u0644\u0627\u0642-\u0627\u0644\u0639\u0646\u0627\u0646-\u0644\u0644\u0623\u0644\u0639\u0627\u0628-45-\u0637\u0631\u064a\u0642\u0629-\u062f\u0641\u0639-\u0639\u0644\u0649-\u0637\u0645\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","og_description":"\u0641\u064a \u0627\u0644\u0639\u0635\u0631 \u0627\u0644\u0631\u0642\u0645\u064a \u0627\u0644\u062d\u0627\u0644\u064a\u060c \u062a\u0639\u062f \u0627\u0644\u0645\u0631\u0648\u0646\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0623\u0645\u0631\u064b\u0627 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629. \u0648\u0644\u0630\u0644\u0643\u060c \u0623\u062d\u062f\u062b \u0645\u062a\u062c\u0631 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 \u062b\u0648\u0631\u0629 \u0641\u064a \u062a\u062c\u0631\u0628\u0629 \u0634\u0631\u0627\u0621 \u0627\u0644\u0623\u0644\u0639\u0627\u0628 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u062c\u0645\u0648\u0639\u0629 \u0631\u0627\u0626\u0639\u0629 \u0645\u0646 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0645\u062e\u062a\u0644\u0641\u0629. \u064a\u062a\u0637\u0631\u0642 \u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u0634\u0648\u0631 \u0625\u0644\u0649 \u0643\u064a\u0641\u064a\u0629 \u062a\u0645\u0643\u064a\u0646 \u062e\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0647\u0630\u0647 \u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633. \u0642\u0648\u0629 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631 \u0641\u064a \u0637\u0631\u0642 \u0627\u0644\u062f\u0641\u0639 \u0645\u0639 45 \u062e\u064a\u0627\u0631\u064b\u0627 [&hellip;]","og_url":"https:\/\/blog.tamatemplus.com\/ar\/\u0625\u0637\u0644\u0627\u0642-\u0627\u0644\u0639\u0646\u0627\u0646-\u0644\u0644\u0623\u0644\u0639\u0627\u0628-45-\u0637\u0631\u064a\u0642\u0629-\u062f\u0641\u0639-\u0639\u0644\u0649-\u0637\u0645\/","og_site_name":"\u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","article_published_time":"2024-01-25T12:09:07+00:00","article_modified_time":"2024-02-28T12:48:14+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png","type":"image\/png"}],"author":"Tamatem Plus","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"Tamatem Plus","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#article","isPartOf":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/"},"author":{"name":"Tamatem Plus","@id":"https:\/\/blog.tamatemplus.com\/ar\/#\/schema\/person\/d65a0484622d86e27361954aabfdbca7"},"headline":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","datePublished":"2024-01-25T12:09:07+00:00","dateModified":"2024-02-28T12:48:14+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/"},"wordCount":6,"image":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png","articleSection":["\u0627\u062d\u0635\u0627\u0626\u064a\u0627\u062a","\u0627\u062e\u0628\u0627\u0631"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/","url":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/","name":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633 - \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","isPartOf":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#primaryimage"},"image":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png","datePublished":"2024-01-25T12:09:07+00:00","dateModified":"2024-02-28T12:48:14+00:00","author":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/#\/schema\/person\/d65a0484622d86e27361954aabfdbca7"},"breadcrumb":{"@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#primaryimage","url":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png","contentUrl":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/01\/45-Payment-Methods.png","width":1792,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a5%d8%b7%d9%84%d8%a7%d9%82-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%86-%d9%84%d9%84%d8%a3%d9%84%d8%b9%d8%a7%d8%a8-45-%d8%b7%d8%b1%d9%8a%d9%82%d8%a9-%d8%af%d9%81%d8%b9-%d8%b9%d9%84%d9%89-%d8%b7%d9%85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/blog.tamatemplus.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/"},{"@type":"ListItem","position":2,"name":"\u0625\u0637\u0644\u0627\u0642 \u0627\u0644\u0639\u0646\u0627\u0646 \u0644\u0644\u0623\u0644\u0639\u0627\u0628: 45 \u0637\u0631\u064a\u0642\u0629 \u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633"}]},{"@type":"WebSite","@id":"https:\/\/blog.tamatemplus.com\/ar\/#website","url":"https:\/\/blog.tamatemplus.com\/ar\/","name":"\u0637\u0645\u0627\u0637\u0645 \u0628\u0644\u0633","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.tamatemplus.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Person","@id":"https:\/\/blog.tamatemplus.com\/ar\/#\/schema\/person\/d65a0484622d86e27361954aabfdbca7","name":"Tamatem Plus","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/02\/new-tamatem-header-150x150-1.png","url":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/02\/new-tamatem-header-150x150-1.png","contentUrl":"https:\/\/blog.tamatemplus.com\/wp-content\/uploads\/2024\/02\/new-tamatem-header-150x150-1.png","caption":"Tamatem Plus"},"url":"https:\/\/blog.tamatemplus.com\/ar\/author\/tamatemplus\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/posts\/1005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/comments?post=1005"}],"version-history":[{"count":4,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/posts\/1005\/revisions"}],"predecessor-version":[{"id":1009,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/posts\/1005\/revisions\/1009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/media\/786"}],"wp:attachment":[{"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/media?parent=1005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/categories?post=1005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tamatemplus.com\/ar\/wp-json\/wp\/v2\/tags?post=1005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}